{"id":3350,"date":"2018-04-12T13:42:02","date_gmt":"2018-04-12T13:42:02","guid":{"rendered":"http:\/\/www.afm.org\/?p=3350"},"modified":"2018-04-02T13:42:41","modified_gmt":"2018-04-02T13:42:41","slug":"la-fcm-tient-un-sommet-anti-harcelement-de-lindustrie-de-la-musique","status":"publish","type":"post","link":"https:\/\/www.afm.org\/fr\/2018\/04\/la-fcm-tient-un-sommet-anti-harcelement-de-lindustrie-de-la-musique\/","title":{"rendered":"La FCM tient un sommet anti-harc\u00e8lement de l\u2019industrie de la musique"},"content":{"rendered":"<p>Le 1<sup>er<\/sup> mars dernier, \u00e0 Toronto, a eu lieu le lancement par la F\u00e9d\u00e9ration canadienne des musiciens du premier sommet anti-harc\u00e8lement de l\u2019industrie canadienne de la musique. Pr\u00e9sente via Skype, la ministre du Patrimoine canadien, M\u00e9lanie Joly, s\u2019est adress\u00e9e aux participants. En plus d\u2019exprimer son soutien, elle les a invit\u00e9 \u00e0 formuler des politiques que son minist\u00e8re pourra appuyer et nous aider \u00e0 faire appliquer contre les auteurs de harc\u00e8lement. Ont \u00e9galement assist\u00e9 des repr\u00e9sentants des organisations suivantes\u00a0: le Bureau de la ministre du Patrimoine canadien, le minist\u00e8re du Patrimoine canadien, Politiques et programmes de la musique, CARAS\/JUNO, la East Coast Music Association, la Canadian Actors Equity Association, ACTRA Toronto, ACTRA RACS, l\u2019Association canadienne des \u00e9diteurs de musique, la Screen Composers Guild of Canada, le Toronto Arts Council, Music Canada, la Musicians Rights Organization Canada, l\u2019Association des auteurs-compositeurs canadiens, Women In Music Canada, pour ne nommer que celles-ci.<\/p>\n<p>Selon la Directrice g\u00e9n\u00e9rale de l\u2019AFM\/FCM, Liana White, le sommet avait pour but de nous permettre de travailler ensemble \u00e0 la cr\u00e9ation d\u2019une politique contre le harc\u00e8lement au travail et sur les lieux de spectacle, applicable \u00e0 l\u2019\u00e9chelle de l\u2019industrie, pour assurer notre propre protection ainsi que celle de nos coll\u00e8gues et des membres de l\u2019assistance.<\/p>\n<p>L\u2019\u00e9nonc\u00e9 de mission de la FCM affirme notamment qu\u2019on doit se traiter les uns les autres avec respect et dignit\u00e9, sans \u00e9gard \u00e0 l\u2019appartenance ethnique, la religion, le sexe, l\u2019\u00e2ge, l\u2019invalidit\u00e9, la citoyennet\u00e9, l\u2019orientation sexuelle, l\u2019\u00e9tat civil, la situation de famille et l\u2019origine nationale.<\/p>\n<p>Du fait qu\u2019elle renferme les normes les plus \u00e9lev\u00e9es au pays en mati\u00e8re de harc\u00e8lement au travail, la Loi sur la sant\u00e9 et la s\u00e9curit\u00e9 au travail (LSST) de l\u2019Ontario peut s\u2019appliquer \u00e0 l\u2019ensemble des provinces. Elle d\u00e9finit le harc\u00e8lement au travail, ce qui comprend le harc\u00e8lement sexuel au travail, comme suit\u00a0: \u00ab\u00a0[le] fait pour une personne d\u2019adopter une ligne de conduite caract\u00e9ris\u00e9e par des remarques ou des gestes vexatoires contre un travailleur dans un lieu de travail lorsqu\u2019elle sait ou devrait raisonnablement savoir que ces remarques ou ces gestes sont importuns.\u00a0\u00bb<\/p>\n<p>Il peut s\u2019agir notamment\u00a0:<\/p>\n<p>de remarques, de blagues ou d\u2019insinuations destin\u00e9es \u00e0 ridiculiser, intimider ou offenser<\/p>\n<p>de violence verbale, physique ou psychologique<\/p>\n<p>de comportement d\u2019exclusion<\/p>\n<p>de l\u2019affichage ou de la circulation d\u2019images ou autres documents offensants<\/p>\n<p>de harc\u00e8lement criminel<\/p>\n<p>Les membres de la FCM doivent pouvoir b\u00e9n\u00e9ficier, partout et en tout temps, d\u2019un milieu de travail s\u00e9curitaire et respectueux de tous.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 1er mars dernier, \u00e0 Toronto, a eu lieu le lancement par la F\u00e9d\u00e9ration canadienne des musiciens du premier sommet anti-harc\u00e8lement de l\u2019industrie canadienne de la musique. Pr\u00e9sente via Skype, la ministre du Patrimoine canadien, M\u00e9lanie Joly, s\u2019est adress\u00e9e aux participants. En plus d\u2019exprimer son soutien, elle les a invit\u00e9 \u00e0 formuler des politiques que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3350","post","type-post","status-publish","format-standard","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/posts\/3350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/comments?post=3350"}],"version-history":[{"count":1,"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/posts\/3350\/revisions"}],"predecessor-version":[{"id":3352,"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/posts\/3350\/revisions\/3352"}],"wp:attachment":[{"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/media?parent=3350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/categories?post=3350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.afm.org\/fr\/wp-json\/wp\/v2\/tags?post=3350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}